{"id":17,"count":2,"description":"Ouate de cellulose souffl\u00e9e, insuffl\u00e9e et projet\u00e9e, fibre de bois, chanvre, li\u00e8ge, enduit \u00e0 la chaux, perspirance et point de ros\u00e9e sur pis\u00e9, galets roul\u00e9s et moellon. Toute pr\u00e9conisation nomme le support et dit ce qui se passe \u00e0 l'interface isolant\/mur.","link":"https:\/\/bati-vert.fr\/blog\/category\/isolation-bati-ancien\/","name":"Isolation du b\u00e2ti ancien","slug":"isolation-bati-ancien","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/bati-vert.fr\/blog\/wp-json\/wp\/v2\/categories\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bati-vert.fr\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/bati-vert.fr\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/bati-vert.fr\/blog\/wp-json\/wp\/v2\/posts?categories=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}